{"id":89697,"date":"2023-09-22T13:09:41","date_gmt":"2023-09-22T10:09:41","guid":{"rendered":"https:\/\/www.autocritica.ro\/?post_type=live-news&#038;p=89697"},"modified":"2023-09-22T13:09:41","modified_gmt":"2023-09-22T10:09:41","slug":"toyota-gr86-40th-anniversary-editie-speciala-in-japonia","status":"publish","type":"live-news","link":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/","title":{"rendered":"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia"},"content":{"rendered":"<p>\u2022 Toyota a publicat primele imagini \u0219i informa\u021bii referitoare la edi\u021bia special\u0103 GR86 40th Anniversary.<\/p>\n<p>\u2022 Versiunea special\u0103 este dedicat\u0103 exclusiv pie\u021bei din Japonia \u0219i a fost lansat\u0103 cu ocazia anivers\u0103rii celor 40 de ani de la debutul lui AE86 (model considerat a fi urma\u0219 al actualului GR86).<\/p>\n<p>\u2022 Produc\u021bie limitat\u0103 la 200 de unit\u0103\u021bi.<\/p>\n<p>\u2022 Elemente speciale de exterior: dou\u0103 culori de caroserie (Spark Red sau Crystal White Pearl), jante de 18 inchi \u00een nuan\u021ba Dark Gray, stickere cu denumirea edi\u021biei speciale, \u0219i c\u00e2teva accesorii de caroserie vopsite \u00een negru.<\/p>\n<p>\u2022 La interior, versiunea aniversar\u0103 va fi echipat\u0103 cu tapi\u021berie \u00een dou\u0103 culori (ro\u0219u \u0219i negru), elemente decorative pe consola central\u0103, denumirea edi\u021biei speciale pe fe\u021bele portierelor \u0219i pe covora\u0219e.<\/p>\n<p>\u2022 \u00cen plus, exemplarele aniversare vor fi echipate standard cu un sistem de fr\u00e2nare \u00eembun\u0103t\u0103\u021bit (cu elemente Brembo) \u0219i cu amortizoare semnate de Sachs.<\/p>\n<div id='gallery-1' class='gallery galleryid-89697 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-2-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-3-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-4-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5-300x225.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5-1024x768.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5-768x576.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5-1536x1152.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-5-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-6-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-7-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-8-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9-300x225.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9-1024x768.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9-768x576.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9-1536x1152.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-9-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10-300x225.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10-1024x768.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10-768x576.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10-1536x1153.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-10-2048x1537.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11-300x225.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11-1024x768.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11-768x576.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11-1536x1153.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-11-2048x1537.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12-300x225.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12-1024x768.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12-768x576.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12-1536x1153.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-12-2048x1537.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-13-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14-300x169.jpg 300w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14-1024x576.jpg 1024w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14-768x432.jpg 768w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14-1536x864.jpg 1536w, https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-14-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>\u2022 Foto: Toyota<\/p>\n","protected":false},"author":4,"featured_media":89699,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[4395,895],"class_list":["post-89697","live-news","type-live-news","status-publish","has-post-thumbnail","hentry","tag-gr86","tag-toyota"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia - Autocritica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia\" \/>\n<meta property=\"og:description\" content=\"\u2022 Toyota a publicat primele imagini \u0219i informa\u021bii referitoare la edi\u021bia special\u0103 GR86 40th Anniversary. \u2022 Versiunea special\u0103 este dedicat\u0103 exclusiv pie\u021bei\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Autocritica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autocritica.ro\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/\",\"url\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/\",\"name\":\"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia - Autocritica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.autocritica.ro\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/toyota-gr86-40th-anniversary-1.jpg\",\"datePublished\":\"2023-09-22T10:09:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.autocritica.ro\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/toyota-gr86-40th-anniversary-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.autocritica.ro\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/toyota-gr86-40th-anniversary-1.jpg\",\"width\":2400,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Live News\",\"item\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/live-news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/\",\"name\":\"Autocritica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/#organization\",\"name\":\"Autocritica\",\"url\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.autocritica.ro\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-negru.png\",\"contentUrl\":\"https:\\\/\\\/www.autocritica.ro\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-negru.png\",\"width\":300,\"height\":102,\"caption\":\"Autocritica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.autocritica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autocritica.ro\",\"https:\\\/\\\/www.instagram.com\\\/autocritica.ro\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia - Autocritica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/","og_locale":"en_US","og_type":"article","og_title":"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia","og_description":"\u2022 Toyota a publicat primele imagini \u0219i informa\u021bii referitoare la edi\u021bia special\u0103 GR86 40th Anniversary. \u2022 Versiunea special\u0103 este dedicat\u0103 exclusiv pie\u021bei","og_url":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/","og_site_name":"Autocritica","article_publisher":"https:\/\/www.facebook.com\/autocritica.ro","og_image":[{"width":2400,"height":1350,"url":"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/","url":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/","name":"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia - Autocritica","isPartOf":{"@id":"https:\/\/www.autocritica.ro\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/#primaryimage"},"image":{"@id":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1.jpg","datePublished":"2023-09-22T10:09:41+00:00","breadcrumb":{"@id":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/#primaryimage","url":"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1.jpg","contentUrl":"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2023\/09\/toyota-gr86-40th-anniversary-1.jpg","width":2400,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.autocritica.ro\/en\/live-news\/toyota-gr86-40th-anniversary-editie-speciala-in-japonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.autocritica.ro\/en\/"},{"@type":"ListItem","position":2,"name":"Live News","item":"https:\/\/www.autocritica.ro\/en\/live-news\/"},{"@type":"ListItem","position":3,"name":"Toyota GR86 40th Anniversary: edi\u021bie special\u0103 \u00een Japonia"}]},{"@type":"WebSite","@id":"https:\/\/www.autocritica.ro\/en\/#website","url":"https:\/\/www.autocritica.ro\/en\/","name":"Autocritica","description":"","publisher":{"@id":"https:\/\/www.autocritica.ro\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autocritica.ro\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.autocritica.ro\/en\/#organization","name":"Autocritica","url":"https:\/\/www.autocritica.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.autocritica.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2020\/12\/logo-negru.png","contentUrl":"https:\/\/www.autocritica.ro\/wp-content\/uploads\/2020\/12\/logo-negru.png","width":300,"height":102,"caption":"Autocritica"},"image":{"@id":"https:\/\/www.autocritica.ro\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autocritica.ro","https:\/\/www.instagram.com\/autocritica.ro\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/live-news\/89697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/live-news"}],"about":[{"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/types\/live-news"}],"author":[{"embeddable":true,"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/comments?post=89697"}],"version-history":[{"count":2,"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/live-news\/89697\/revisions"}],"predecessor-version":[{"id":89713,"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/live-news\/89697\/revisions\/89713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/media\/89699"}],"wp:attachment":[{"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/media?parent=89697"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autocritica.ro\/en\/wp-json\/wp\/v2\/tags?post=89697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}